{"id":2467,"date":"2018-05-29T14:45:19","date_gmt":"2018-05-29T14:45:19","guid":{"rendered":"http:\/\/chinese-boxing-institute.de\/?p=2467"},"modified":"2018-09-13T10:35:56","modified_gmt":"2018-09-13T10:35:56","slug":"neuerscheinung-chinese-boxing-innere-chinesische-kampfkunst","status":"publish","type":"post","link":"https:\/\/chinese-boxing-institute.de\/chinese-boxing-starten\/neuerscheinung-chinese-boxing-innere-chinesische-kampfkunst\/","title":{"rendered":"Neuerscheinung: Chinese Boxing, Innere Chinesische Kampfkunst"},"content":{"rendered":"<p>[vc_row][vc_column][vc_column_text]<a href=\"https:\/\/www.amazon.de\/Chinese-Boxing-Innere-Chinesische-Kampfkunst\/dp\/1987756606\/ref=sr_1_1?ie=UTF8&amp;qid=1529675461&amp;sr=8-1&amp;keywords=chinese+boxing\" target=\"_blank\" rel=\"noopener\"><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft wp-image-79 size-medium\" src=\"http:\/\/chinese-boxing-institute.de\/wp-content\/uploads\/2017\/12\/chinese_boxing_buch-212x300.jpg\" alt=\"\" width=\"212\" height=\"300\" srcset=\"https:\/\/chinese-boxing-institute.de\/wp-content\/uploads\/2017\/12\/chinese_boxing_buch-212x300.jpg 212w, https:\/\/chinese-boxing-institute.de\/wp-content\/uploads\/2017\/12\/chinese_boxing_buch-768x1086.jpg 768w, https:\/\/chinese-boxing-institute.de\/wp-content\/uploads\/2017\/12\/chinese_boxing_buch-724x1024.jpg 724w, https:\/\/chinese-boxing-institute.de\/wp-content\/uploads\/2017\/12\/chinese_boxing_buch.jpg 1273w\" sizes=\"(max-width: 212px) 100vw, 212px\" \/><\/a>Wir leben in einer sich rasant ver\u00e4ndernden Welt und sp\u00e4testens ein Blick in die Nachrichten macht verst\u00e4ndlich, warum viele Menschen sich mit \u00c4ngsten und Bef\u00fcrchtungen bez\u00fcglich ihrer Lebensgestaltung plagen.<\/p>\n<p>Stress und Burnout sind als feste Begriffe in den Medien und der Arbeitsmedizin zu finden und die Anzahl der psychischen Erkrankungen (allen voran Depression) war noch nie derartig hoch. Dabei ist unser Gehirn jedoch in der Interpretation dieser Signale in l\u00e4ngst vergangenen Zeiten stehen geblieben \u2013 die Signale, die unser Gehirn produziert, wenn eine Klassenarbeit ansteht, wenn man vom Chef ger\u00fcgt wird oder sich mit einem Mitb\u00fcrger um den Platz in der Warteschlange im Supermarkt streitet, sind dieselben, die unsere Vorfahren aus der Steinzeit angesichts eines gro\u00dfen Raubtiers empfangen haben. Diese sollen den K\u00f6rper auf eine physische Reaktion in Form von Flucht oder Angriff vorbereiten.<\/p>\n<p>Nur ist es heute so, dass die meisten Stressmomente eben nicht physisch in Form von Kampf oder Flucht gel\u00f6st werden k\u00f6nnen. Vielmehr gibt man sich verbalen Streitereien hin, schluckt den \u00c4rger und die Kr\u00e4nkung runter (Magenbeschwerden), knirscht mit den Z\u00e4hnen (Zahnsch\u00e4den, dauerhafte Verspannungen), zieht sinnbildlich den Kopf ein (Nackenverspannungen) und versucht, auf die verschiedensten Arten und Weisen mit der Situation fertigzuwerden, w\u00e4hrend der K\u00f6rper einfach nur Bewegung will.<\/p>\n<p>Dabei spielen sich viele Spannungen und Konflikte im Unbewussten ab. Ihre Effekte werden dort zun\u00e4chst unbemerkt vom Individuum behandelt. Daher ist es umso wichtiger, das Bewusstsein gleicherma\u00dfen mit dem K\u00f6rper zu schulen und so letztlich Zugriff auf unbewusste Prozesse zu erlangen. Diese Prozesse machen sich h\u00e4ufig durch ihre Manifestation im K\u00f6rper (wie die oben beschriebenen Erscheinungen) bemerkbar, bevor jemand \u00fcberhaupt bewusst benennen k\u00f6nnte, dass etwas \u201eschief\u201c l\u00e4uft.<\/p>\n<p>Das Chinesische Boxen schult die Wahrnehmung des eigenen K\u00f6rpers und lehrt das L\u00f6sen von Verspannungen durch gelenkte Aufmerksamkeit. Mit dem Trainingsfortschritt erlangen Trainierende eine entspannte und lockere K\u00f6rperhaltung sowie Achtsamkeit gegen\u00fcber sich selbst und der Umgebung. Damit geht ein Verlust an hinderlichen Alltags\u00e4ngsten einher. Die positiven psychischen Aspekte des \u201efighting mind\u201c f\u00fchren zu einer lockeren und entspannten, in die Breite und Tiefe der Welt gerichteten Wahrnehmung. Die Kombination aus Offenheit, Lernbereitschaft und Anpassungsf\u00e4higkeit, die von einer inneren \u00dcberzeugung der Wehrhaftigkeit und Handlungsf\u00e4higkeit begleitet wird, stellt die von den Autoren angestrebte Haltung hinter der inneren Kampfkunst des Chinesischen Boxens dar.<\/p>\n<p>Generell geh\u00f6ren nach Ansicht der Autoren Grundkenntnisse in irgendeiner Art der Selbstverteidigung zum Basiswissen eines gebildeten Menschen, v\u00f6llig unbeeinflusst von der Entscheidung, dieses Wissen und K\u00f6nnen auch tats\u00e4chlich anwenden zu wollen. Die Angst, sich nicht wehren zu k\u00f6nnen, ist nach Ansicht der Autoren h\u00e4ufig genauso sch\u00e4dlich wie ein tats\u00e4chlich stattgefundener \u00dcbergriff.<\/p>\n<p>Dieses erste deutschsprachige Grundlagenwerk bietet daf\u00fcr ausf\u00fchrliche Erkl\u00e4rungen zur K\u00f6rperarbeit, Basistechniken und Einzel- sowie auch Partner\u00fcbungen \u2013 unterst\u00fctzt von Videolinks zum einfacheren Verst\u00e4ndnis. Es ist ein stil\u00fcbergreifendes Grundlagenbuch, das jedem Kampfk\u00fcnstler und an Kampfkunst Interessierten beim Entdecken und Entwickeln der eigenen Energie und F\u00e4higkeiten unterst\u00fctzen will.<\/p>\n<p>Dazu geh\u00f6ren neben einem ausf\u00fchrlichen \u00dcbungsteil historische Zusammenh\u00e4nge und auch eine Analyse der rechtlichen Situation von Kampfk\u00fcnstlern im Ernstfall.<\/p>\n<p>Das Buch ist bei <a href=\"https:\/\/www.amazon.de\/Chinese-Boxing-Innere-Chinesische-Kampfkunst\/dp\/1987756606\/ref=sr_1_1?ie=UTF8&amp;qid=1529675461&amp;sr=8-1&amp;keywords=chinese+boxing\" target=\"_blank\" rel=\"noopener\">Amazon<\/a> erschienen.[\/vc_column_text][\/vc_column][\/vc_row]<\/p>","protected":false},"excerpt":{"rendered":"<p>Chinese Boxing schult die Wahrnehmung des eigenen K\u00f6rpers und lehrt das L\u00f6sen von Verspannungen durch gelenkte Aufmerksamkeit. <\/p>\n","protected":false},"author":2,"featured_media":79,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[24],"tags":[58,57,59,56,60],"_links":{"self":[{"href":"https:\/\/chinese-boxing-institute.de\/chinese-boxing-starten\/wp-json\/wp\/v2\/posts\/2467"}],"collection":[{"href":"https:\/\/chinese-boxing-institute.de\/chinese-boxing-starten\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/chinese-boxing-institute.de\/chinese-boxing-starten\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/chinese-boxing-institute.de\/chinese-boxing-starten\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/chinese-boxing-institute.de\/chinese-boxing-starten\/wp-json\/wp\/v2\/comments?post=2467"}],"version-history":[{"count":7,"href":"https:\/\/chinese-boxing-institute.de\/chinese-boxing-starten\/wp-json\/wp\/v2\/posts\/2467\/revisions"}],"predecessor-version":[{"id":15402,"href":"https:\/\/chinese-boxing-institute.de\/chinese-boxing-starten\/wp-json\/wp\/v2\/posts\/2467\/revisions\/15402"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/chinese-boxing-institute.de\/chinese-boxing-starten\/wp-json\/wp\/v2\/media\/79"}],"wp:attachment":[{"href":"https:\/\/chinese-boxing-institute.de\/chinese-boxing-starten\/wp-json\/wp\/v2\/media?parent=2467"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/chinese-boxing-institute.de\/chinese-boxing-starten\/wp-json\/wp\/v2\/categories?post=2467"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/chinese-boxing-institute.de\/chinese-boxing-starten\/wp-json\/wp\/v2\/tags?post=2467"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}