{"id":15382,"date":"2018-09-12T09:32:21","date_gmt":"2018-09-12T09:32:21","guid":{"rendered":"http:\/\/chinese-boxing-institute.de\/?p=15382"},"modified":"2024-04-19T09:21:33","modified_gmt":"2024-04-19T09:21:33","slug":"peine-10-11-2018-und-19-01-2019-selbstverteidigungsworkshop-an-der-vhs","status":"publish","type":"post","link":"https:\/\/chinese-boxing-institute.de\/chinese-boxing-starten\/peine-10-11-2018-und-19-01-2019-selbstverteidigungsworkshop-an-der-vhs\/","title":{"rendered":"Peine, 10.11.2018 und 19.01.2019  Selbstverteidigungsworkshop an der VHS"},"content":{"rendered":"<p>Als Tagesseminar stehen die beiden Termine unter der \u00dcberschrift: Selbstverteidigung muss einfach sein! Das Programm ist seri\u00f6s und in kurzer Zeit anwendbar. Lernen Sie neben theoretischen Grundlagen vorausschauende und effektive praktische Techniken zur Universalverteidigung kennen. Auch auf den Einsatz von Hilfsmitteln, wie z.B. Schl\u00fcssel oder Regenschirm, wird eingegangen.<\/p>\n<p>Mehr Informationen und Anmeldung unter:\u00a0<a href=\"https:\/\/www.kvhs-peine.de\/Kurssuche-Dozent-Kursliste.227078805.226151399.html?dozent=R%C3%B6der%2C+Karsten\" target=\"_blank\" rel=\"noopener\">kvhs-peine<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>Als Tagesseminar stehen die beiden Termine unter der \u00dcberschrift: Selbstverteidigung muss einfach sein!<\/p>\n","protected":false},"author":2,"featured_media":15363,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[77],"tags":[],"_links":{"self":[{"href":"https:\/\/chinese-boxing-institute.de\/chinese-boxing-starten\/wp-json\/wp\/v2\/posts\/15382"}],"collection":[{"href":"https:\/\/chinese-boxing-institute.de\/chinese-boxing-starten\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/chinese-boxing-institute.de\/chinese-boxing-starten\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/chinese-boxing-institute.de\/chinese-boxing-starten\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/chinese-boxing-institute.de\/chinese-boxing-starten\/wp-json\/wp\/v2\/comments?post=15382"}],"version-history":[{"count":5,"href":"https:\/\/chinese-boxing-institute.de\/chinese-boxing-starten\/wp-json\/wp\/v2\/posts\/15382\/revisions"}],"predecessor-version":[{"id":16390,"href":"https:\/\/chinese-boxing-institute.de\/chinese-boxing-starten\/wp-json\/wp\/v2\/posts\/15382\/revisions\/16390"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/chinese-boxing-institute.de\/chinese-boxing-starten\/wp-json\/wp\/v2\/media\/15363"}],"wp:attachment":[{"href":"https:\/\/chinese-boxing-institute.de\/chinese-boxing-starten\/wp-json\/wp\/v2\/media?parent=15382"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/chinese-boxing-institute.de\/chinese-boxing-starten\/wp-json\/wp\/v2\/categories?post=15382"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/chinese-boxing-institute.de\/chinese-boxing-starten\/wp-json\/wp\/v2\/tags?post=15382"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}