{"id":15379,"date":"2018-09-12T09:25:37","date_gmt":"2018-09-12T09:25:37","guid":{"rendered":"http:\/\/chinese-boxing-institute.de\/?p=15379"},"modified":"2024-04-19T09:22:23","modified_gmt":"2024-04-19T09:22:23","slug":"hamburg-18-09-11-12-2018-selbstverteidigungstraining-beim-vaf","status":"publish","type":"post","link":"https:\/\/chinese-boxing-institute.de\/chinese-boxing-starten\/hamburg-18-09-11-12-2018-selbstverteidigungstraining-beim-vaf\/","title":{"rendered":"Hamburg, 18.09. &#8211; 11.12.2018  Selbstverteidigungstraining beim VAF"},"content":{"rendered":"<p>Dieser Kurs vermittelt an 12 Terminen die Grundlagen einer effektiven und angemessenen Selbstverteidigung. In lockerer Atmosph\u00e4re werden von Jakob Ungerer und Dirk Wetter die Grundprinzipien und technischen Abl\u00e4ufe vermittelt. Teilnehmende bekommen einen Einblick, was funktioniert und was nicht &#8211; rein pragmatisch und ohne Kampfkunststile. F\u00fcr M\u00e4nner und Frauen gleicherma\u00dfen geeignet. Vorkenntnisse sind nicht erforderlich.<\/p>\n<p>Mehr Informationen und Anmeldung unter:\u00a0<a href=\"https:\/\/vafev.de\/sportfinder?kurs=alle&amp;altersgruppe=alle&amp;zeit=dienstag\" target=\"_blank\" rel=\"noopener\">vafev<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>Dieser Kurs vermittelt an 12 Terminen die Grundlagen einer effektiven und angemessenen Selbstverteidigung. <\/p>\n","protected":false},"author":2,"featured_media":15380,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[77],"tags":[],"_links":{"self":[{"href":"https:\/\/chinese-boxing-institute.de\/chinese-boxing-starten\/wp-json\/wp\/v2\/posts\/15379"}],"collection":[{"href":"https:\/\/chinese-boxing-institute.de\/chinese-boxing-starten\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/chinese-boxing-institute.de\/chinese-boxing-starten\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/chinese-boxing-institute.de\/chinese-boxing-starten\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/chinese-boxing-institute.de\/chinese-boxing-starten\/wp-json\/wp\/v2\/comments?post=15379"}],"version-history":[{"count":5,"href":"https:\/\/chinese-boxing-institute.de\/chinese-boxing-starten\/wp-json\/wp\/v2\/posts\/15379\/revisions"}],"predecessor-version":[{"id":16391,"href":"https:\/\/chinese-boxing-institute.de\/chinese-boxing-starten\/wp-json\/wp\/v2\/posts\/15379\/revisions\/16391"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/chinese-boxing-institute.de\/chinese-boxing-starten\/wp-json\/wp\/v2\/media\/15380"}],"wp:attachment":[{"href":"https:\/\/chinese-boxing-institute.de\/chinese-boxing-starten\/wp-json\/wp\/v2\/media?parent=15379"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/chinese-boxing-institute.de\/chinese-boxing-starten\/wp-json\/wp\/v2\/categories?post=15379"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/chinese-boxing-institute.de\/chinese-boxing-starten\/wp-json\/wp\/v2\/tags?post=15379"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}