{"id":15224,"date":"2018-07-11T16:40:15","date_gmt":"2018-07-11T16:40:15","guid":{"rendered":"http:\/\/chinese-boxing-institute.de\/?p=15224"},"modified":"2024-04-19T08:55:34","modified_gmt":"2024-04-19T08:55:34","slug":"interview-james-cravens","status":"publish","type":"post","link":"https:\/\/chinese-boxing-institute.de\/chinese-boxing-starten\/interview-james-cravens\/","title":{"rendered":"Interview: James Cravens"},"content":{"rendered":"<h4 class=\"p1\" style=\"text-align: center;\"><em>\u201eEs gibt keinen Weg, ein guter K\u00e4mpfer zu werden, ohne manche Sachen durchzumachen. Aber es gibt so viel dummes Training, das nur dem K\u00f6rper schadet und nichts erreicht, au\u00dfer dich ein bisschen abzuh\u00e4rten.\u201c<\/em><\/h4>\n<h5 class=\"p1\">Fu\u0308r das folgende Interview haben James Cravens und Olaf Pachten sich fu\u0308r einige Wochen E-Mails hin- und hergeschrieben und sich schlie\u00dflich fu\u0308r einen Sonntagnachmittag (bzw. -vormittag in Florida, wo Cravens lebt) entschieden, um das Gespr\u00e4ch per Skype fu\u0308hren zu k\u00f6nnen. James Cravens sitzt in seinem Wohnzimmer auf der Couch und ist w\u00e4hrend des Gespr\u00e4chs sehr konzentriert. Ab und zu blitzt sein Humor auf, besonders wenn es um Anekdoten aus der Zeit mit seinem Lehrer Christopher Casey geht.<\/h5>\n<p><strong>James, wann hast du angefangen, das Chinesische Boxen zu erlernen?<\/strong><\/p>\n<p>Ich habe 1973 angefangen, bei Mr. Casey zu trainieren. Zu dieser Zeit unterrichtete er haupts\u00e4chlich <em>Kenpo<\/em> und sein <em>Chin Na<\/em>. Er unterrichtete auch etwas <em>Hsing-I<\/em> und einige kleinere Teile <em>Bagua<\/em>, aber ich denke, dass er in dieser Zeit seine <em>Chinese Boxing <\/em>Theorie entwickelte. Er unterrichtete an der \u201eGeorgia-Tech\u201c in Atlanta und ich war zu dieser Zeit noch bei meinem alten Lehrer. Der gab mir jedoch die Erlaubnis, mit Casey zu trainieren, wann immer ich Lust dazu h\u00e4tte. Er hatte einen Club an der \u201eGeorgia Tech University\u201c, einer Fachschule fu\u0308r Maschinenbau, und unterrichtete dort eine Gruppe von Studenten. Ich ging zu ihm, um <em>Kenpo\u00a0<\/em>und einige andere Dinge zu lernen, aber ich denke, zu dieser Zeit war er mehr daran interessiert, seine Theorie zu entwickeln.<\/p>\n<p>1976 wurde ich offiziell sein Schu\u0308ler. Ich verlie\u00df meine andere Gruppe, ging ganz zu Mr. Casey, und er begann damit, das <em>Kenpo Curriculum<\/em> und einige andere Dinge, die ich bei ihm begonnen hatte, zu vervollst\u00e4ndigen. Innerhalb dieser vier Jahre lernte ich <em>Wing Chun<\/em>, <em>Chin Na<\/em>, einige <em>Bagua<\/em> Teile und <em>Hsing-I\u00a0<\/em>von ihm.<\/p>\n<p>Die Entwicklung seiner <em>Chinese Boxing <\/em>Theorie kam wohl erst zum Zeitpunkt seiner Abreise nach Deutschland zur vollen Entfaltung. Ich denke, dass Manfred Steiner dabei eine Rolle gespielt hat, ihm zu helfen, seine Theorie darin zu u\u0308berpru\u0308fen, ob sie auch gegen einen so starken Gegner wie Manfred bestehen wu\u0308rde. Das war ein wichtiges Element in seiner Entwicklung.<\/p>\n<p><strong>Du hast geschrieben, dass sich nach seiner Ru\u0308ckkehr aus Deutschland die <em>Chinese Boxing<\/em>\u00a0<\/strong><strong>Boards entwickelten. Wenn man diese studiert, f\u00e4llt auf, dass darin wirklich eine Menge\u00a0<\/strong><strong>Information enthalten ist. Wo sollte man deiner Meinung nach mit einem Anf\u00e4nger\u00a0<\/strong><strong>beginnen? Unterrichtest du die Basistechniken, oder bist du der Meinung, dass einer der\u00a0<\/strong><strong>traditionellen Stile hilfreicher ist, um einen Einstieg in das<em> Chinesische Boxen<\/em> zu bekommen?<\/strong><\/p>\n<p>Genau genommen haben die Boards einen Entwicklungsprozess durchlaufen. Ich trainierte damals alle drei Monate fu\u0308r eine Woche bei ihm und wenn ich zuru\u0308ckkam, wollten meine Schu\u0308ler immer das lernen, was er mir beigebracht hatte. Nach einiger Zeit wurde uns klar, dass dies zu unzusammenh\u00e4ngend war. Mr. Casey rief mich oft an und fragte mich, was meine Schu\u0308ler sagen wu\u0308rden. Ich erkl\u00e4rte ihm die Situation und das veranlasste ihn zu der Idee, die <em>Chinese Boxing Boards<\/em> zu entwickeln. Einer seiner fru\u0308heren Lehrer vom \u201eAmerican Jiujitsu Institute\u201c in Hawaii hatte diese Methode, seine Kampfkunst zu unterrichten. Im <em>Jiujitsu<\/em> haben sie die Wu\u0308rfe, den Bodenkampf, ein kleineres <em>Chin Na<\/em> Board usw. Er war der Meinung, dies sei eine gute Idee, also stellte er ein Set aus zehn Boards mit jeweils 25 Punkten zusammen. Er erz\u00e4hlte mir, dass er sie nicht danach organisiert hatte, was ein Anf\u00e4nger lernen sollte, sondern dass es eine Zusammenstellung der Sachen sei, die ihm am besten gefielen.<\/p>\n<p>Also begannen wir zu unterrichten und die Frage war: Was ist mit dem Training der inneren Kampfku\u0308nste und der anderen Formen wie z.B. <em>Wing Chun<\/em> und <em>White Crane<\/em>? Er hatte ein Board zu den Formen, in das er <em>Tai Chi,<\/em> <em>Bagua<\/em>, <em>Hsing-I<\/em>, <em>Wing Chun<\/em> und <em>Monkey Boxing<\/em> packte. Aber er sagte mir, hinsichtlich der Form glaube er daran, dass es wahrscheinlich ausreichen wu\u0308rde, wenn man nur eine innere Bewegungsart u\u0308bt, und dass man dazu die Techniken der Boards lernen k\u00f6nnte, aber dabei zumindest eine innere Basis der Bewegung haben wu\u0308rde.<\/p>\n<p>Nach seinem Tod blieb mir nichts anderes u\u0308brig, als die einzelnen Teile zusammenzufu\u0308gen, und mir wurde klar, dass die Boards nicht so organisiert waren, dass sie von Anf\u00e4ngern zu Fortgeschrittenen fu\u0308hrten. Meine ersten Gedanken waren noch etwas unausgereift. Ich zog nach Florida um und wollte nicht, dass die Boards irgendetwas von dem, was er unterrichtet hatte, auslie\u00dfen. (lacht!)<\/p>\n<p>Ich meine, diese Boards, die ich zusammengestellt hatte, waren gigantisch! Ich hatte ungef\u00e4hr 16 Boards und die Boards beinhalteten ungef\u00e4hr 50 oder 60 Sachen, weil ich alles aus den unterschiedlichen Curricula dort hinein gepackt hatte. Es hat nicht allzu lange gedauert, bis ich merkte, dass es so nicht funktionieren wu\u0308rde. Die Leute waren damit u\u0308berfordert und ich h\u00e4tte das von Anfang an verstehen mu\u0308ssen, aber ich wollte einfach alles von dem, was er unterrichtet hatte, erhalten. Das wirkliche Problem war, dass ich die Hauptbotschaft, die er unterrichtete, vergessen hatte. Du musst zu dem Einfachen zuru\u0308ckkehren und verstehen, dass die Vielzahl der Techniken keinen Sinn macht ohne die Grundlagen der einfachen Prinzipien. Das ist eine Lektion, die ich seitdem mehrfach gelernt habe, und so kam ich dazu, die kleineren Boards zu entwerfen, die wir heute die <em>Chinese Boxing Core Synthesis Boards<\/em> nennen.<\/p>\n<p>Ich behielt die 16 Boards, die ich anf\u00e4nglich entworfen hatte, reduzierte aber die Anzahl der Sachen auf jedem Board auf 12. Zudem ordnete ich die Techniken so, wie ich sie einem Anf\u00e4nger beibringen wu\u0308rde, um dann auf einen h\u00f6heren Level fortschreiten zu k\u00f6nnen. Begleitend dazu fu\u0308gte ich etwas zusammen, von dem Casey viel gesprochen hatte, aber es nie in einer geordneten Form herausgebracht hatte: das <em>Chinese Boxing Encounter<\/em> (das Aufeinandertreffen\/Gefecht im <em>Chinese Boxing<\/em>). Das ist das Studium von Entry (Eingang), das Studium von Touch (Beru\u0308hrung) und das Studium vom Finish (Beenden) im realistischen Zweikampf. Innerhalb der Lehren des Encounter k\u00f6nnen wir jede Technik verstehen und wie diese Technik im Encounter ihr Ziel erreicht. Du kannst sogar zu den einfachen Synthesis Boards gehen und dir eine Technik aussuchen und herausfinden, wie diese Technik in das Encounter passt. Das gibt uns eine wesentlich rationalere Herangehensweise an das Boxen, anstatt zu sagen: \u201eLass uns das Hand-Board durchgehen mit all seinen Techniken, dann lass uns das Fu\u00df-Board durchgehen und dann lass uns sehen, wie wir das im K\u00e4mpfen anwenden.\u201c Das Encounter in seinen drei Teilen zu verstehen, hilft uns sehr dabei, alle einzelnen Techniken zu verstehen.<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter wp-image-15226 size-full\" src=\"http:\/\/chinese-boxing-institute.de\/wp-content\/uploads\/2018\/07\/James-Eric.jpg\" alt=\"\" width=\"907\" height=\"627\" srcset=\"https:\/\/chinese-boxing-institute.de\/wp-content\/uploads\/2018\/07\/James-Eric.jpg 907w, https:\/\/chinese-boxing-institute.de\/wp-content\/uploads\/2018\/07\/James-Eric-300x207.jpg 300w, https:\/\/chinese-boxing-institute.de\/wp-content\/uploads\/2018\/07\/James-Eric-768x531.jpg 768w\" sizes=\"(max-width: 907px) 100vw, 907px\" \/><\/p>\n<p class=\"p1\">Den Unterricht der alten Stile betreffend, ist das genau so m\u00f6glich. Es h\u00e4ngt davon ab, was du betonen m\u00f6chtest. Wenn du deinen Schu\u0308lern den besten Weg aufzeigen willst, Kampff\u00e4higkeiten zu entwickeln, dann bietet das Synthesis Board<span class=\"Apple-converted-space\">\u00a0<\/span>alle effizienten Techniken. Wenn also jemand all dies tut und die <em>Chinese Boxing<\/em> Theorie<span class=\"Apple-converted-space\">\u00a0<\/span>dabei nutzt, muss er die Prinzipien von Verwurzeln, Nachgeben, Durchl\u00e4ssigkeit, ganzheitlicher Bewegung, Wandlungsf\u00e4higkeit, starker Projektion, Zentrierung usw. entwickeln. Wie man das machen soll?<\/p>\n<p class=\"p1\">Du kannst das tun, indem du an den Bewegungen des Encounter<span class=\"Apple-converted-space\">\u00a0<\/span>arbeitest. Aber ich denke, der bessere Weg ist es, sich in einer der inneren Kampfku\u0308nste zu bewegen. Wenn man das gut kann, wenn man in der Lage ist, sich viele Minuten zu bewegen und dabei eine Wurzel, eine wandlungsf\u00e4hige Balance, eine ganzheitliche Bewegung usw. beizubehalten, ver\u00e4ndert das eine Menge an der Art und Weise, wie jemand steht und sich bewegt. Diese Angewohnheiten mu\u0308ssen erlernt werden und dann k\u00f6nnen sie hinter den Techniken stehen, anstatt dass die Techniken hohl und leer sind. Die Stile k\u00f6nnen fu\u0308r sich selbst gelernt werden und dann kann jemand, der den Zweikampf versteht, einem beibringen, sie in der Art des <em>Chinesischen Boxens<\/em> anzuwenden. Meiner Meinung nach kann ich das besser durch die Synthesis Boards,<span class=\"Apple-converted-space\">\u00a0<\/span>w\u00e4hrend ich einen Schu\u0308ler dazu bringe, eine der inneren Bewegungen zu machen.<\/p>\n<p class=\"p1\"><strong>Wie unterrichtest du heute?<\/strong><\/p>\n<p class=\"p1\">Heute bin ich \u00e4lter und bringe einer Menge alter Menschen die inneren Bewegungsku\u0308nste bei, haupts\u00e4chlich <em>Tai Chi<\/em> fu\u0308r die Gesundheit. Ich unterrichte viel davon. Etwa 30\u201335% meiner Schu\u0308ler sind immer noch etwas ju\u0308nger und machen <em>Chinese Boxing<\/em>. Ich habe eine Gruppe in Tennessee, die ich alle Vierteljahre unterrichte, und ich habe eine Handvoll Privatschu\u0308ler hier, die ich unterrichte. Die meisten davon sind Langzeitschu\u0308ler und seit Jahren bei mir.<\/p>\n<p class=\"p1\">Wir arbeiten an Sachen innerhalb des Encounter und an Dingen, die den jeweiligen Schu\u0308ler interessieren. Manchmal kommen diejenigen, die <em>Chinese Boxing<\/em> machen, in Paaren zusammen und manchmal arbeite ich mit einzelnen Schu\u0308lern. Es entwickelt sich also immer noch speziell unter den Ju\u0308ngeren und manche der \u00c4lteren haben auch immer noch Interesse, jedoch kein Interesse mehr daran, verletzt zu werden. Wir haben durch unsere eigenen Fehler eine Menge dazugelernt, was die Sicherheit angeht. Wenn du eine Kampfkunst erlernst, deren <img decoding=\"async\" class=\"alignleft wp-image-15227 size-full\" src=\"http:\/\/chinese-boxing-institute.de\/wp-content\/uploads\/2018\/07\/James-Rick-Bill.jpg\" alt=\"\" width=\"461\" height=\"367\" srcset=\"https:\/\/chinese-boxing-institute.de\/wp-content\/uploads\/2018\/07\/James-Rick-Bill.jpg 461w, https:\/\/chinese-boxing-institute.de\/wp-content\/uploads\/2018\/07\/James-Rick-Bill-300x239.jpg 300w\" sizes=\"(max-width: 461px) 100vw, 461px\" \/>Schwerpunkt darin liegt, in einer Situation auf Leben und Tod zu k\u00e4mpfen, hast du eine Menge Schwierigkeiten, mit denen du umgehen musst. Du musst entscheiden, wie du die eine oder andere Aktion trainierst, ohne dich dabei st\u00e4ndig gegenseitig zu verletzen. Das war eine wirkliche Herausforderung in all den Jahren. Wenn du ju\u0308nger bist, dann denkst du nicht viel daru\u0308ber nach, machst dir keine Sorgen. Manchmal blickst du zuru\u0308ck und denkst dir: \u201eWow, wir h\u00e4tten uns dabei wirklich b\u00f6se verletzen k\u00f6nnen, wir haben echt Glu\u0308ck gehabt\u201c, wei\u00dft du? (lacht!)<\/p>\n<p class=\"p1\">Du wirst also \u00e4lter und achtest darauf und hoffst, den Ju\u0308ngeren dabei zu helfen, unn\u00f6tige Verletzungen zu vermeiden. Ich meine, es gibt keinen Weg, ein guter K\u00e4mpfer zu werden, ohne manche Sachen durchzumachen. Aber es gibt so viel dummes Training, das nur dem K\u00f6rper schadet und nichts erreicht, au\u00dfer dich ein bisschen abzuh\u00e4rten. Abh\u00e4rtung ist wichtig, aber die meisten meiner Probleme, Schmerzen und Einschr\u00e4nkungen heute im Alter sind direkt auf dieses dumme Training zuru\u0308ckzufu\u0308hren. (lacht!)<\/p>\n<p class=\"p1\">Es ist so bl\u00f6d, dass du erst alt werden musst, um etwas weise zu werden. Wenn man diese Weisheit nur schon h\u00e4tte, solange man jung ist! (lacht!)<\/p>\n<p class=\"p1\"><strong>Wie ist die Verbindung zu Detlef Zimmermann zustande gekommen und wann bist du das erste Mal nach Deutschland gereist?<\/strong><\/p>\n<p class=\"p1\">Die erste Verbindung zu Detlef war Stefan, einer seiner Schu\u0308ler. Er war ein langj\u00e4hriger Schu\u0308ler. Ich kannte Detlef nicht wirklich gut. Ich glaube, ich hatte ein Bild von Manfreds Gruppe und darauf war auch Detlef abgebildet. Aber ich wusste nicht, wer er war, und glaube auch nicht, dass er von mir wusste. Aber als ich anfing, das Internet zu nutzen und eine Webseite aufgebaut hatte, muss Stefan diese Seite gesehen und mit Detlef daru\u0308ber gesprochen haben. Er hat ihm gesagt, dass er zum Trainieren hierher kommen wolle, da ihm klar geworden war, dass ich mit Casey studiert hatte.<\/p>\n<p class=\"p1\">Also kam Stefan hierher und rief mich an, als er im Urlaub in der Gegend war. Er sagte, er sei fu\u0308r zwei oder drei Wochen in der Stadt und wolle gern an meinem Unterricht teilnehmen. Also haben wir uns getroffen, um ein bisschen Push Hands zusammen zu trainieren. Das war das, was er wollte, und ich bemerkte, dass, wenn er pushte, dies nicht unbedingt <em>Tai Chi<\/em> war. Ich konnte sehen, dass er das Zentrum verstand und ein gutes Konzept davon im Kopf hatte, aber was er eigentlich machte, war auf eine Gelegenheit zu warten, und wenn er eine fand, so schnell und hart wie m\u00f6glich nach vorne durchzusto\u00dfen, in der Hoffnung, dich aus dem Gleichgewicht zu bringen und umzuhauen. Das war im Grunde genommen sein Push Hands. Er war ein ziemlich athletischer Typ und er war ziemlich gut in dem, was er machte.<\/p>\n<p class=\"p1\">Ich hatte zu dieser Zeit bereits genug Erfahrung und mir war bewusst, dass so etwas passieren k\u00f6nnte, also habe ich mich ganz gut gegen ihn halten k\u00f6nnen. Aber ich habe ihn mit in meinen Unterricht genommen und einige meiner Jungs hatten wirklich Probleme mit diesem Nach-vorne-Durchsto\u00dfen. Ich hatte ihnen vorher nichts erz\u00e4hlt und er stie\u00df nach vorne los und zwei oder drei von den Jungs wurden von ihm umgehauen. Ich erinnere mich, dass ich in den Stunden, an denen er nicht teilnahm, den anderen erkl\u00e4ren musste, was sie falsch gemacht hatten, und so diente er als ein sehr nu\u0308tzliches Werkzeug. (lacht!)<\/p>\n<p class=\"p1\">Stefan ging zuru\u0308ck und muss Detlef erz\u00e4hlt haben, dass es sich lohnen wu\u0308rde, mich heru\u0308berzuholen, und so bekam ich schlie\u00dflich eine Einladung. Also ist das alles mehr oder weniger durch Stefans Besuch entstanden. So hat das Ganze angefangen und ich erinnere mich, als ich das erste Mal nach Deutschland gekommen bin und Detlef eine Privatstunde haben wollte, um Push Hands zu machen (lacht!) &#8230; da wusste ich, was auf mich zukommen wu\u0308rde. (lacht!)<\/p>\n<p class=\"p1\"><strong>Wei\u00dft du, was Mr. Casey gemacht hat, bevor er in die Internationalen Versicherungen eingestiegen ist, bevor er nach Deutschland kam?<\/strong><\/p>\n<p class=\"p1\">Er wuchs in Atlanta Georgia auf und war ein hochbegabtes Kind. Seine Mutter war eine Lehrerin im \u00f6ffentlichen Schuldienst und eine Lehrerin fu\u0308r hochbegabte Kinder. Sie hatte zwei Kinder. Chris und seine Schwester, die ebenfalls hochbegabt war. Als Chris sieben oder acht Jahre alt war, fand er heraus, dass in der Stadt ein <em>Jiujitsu<\/em><span class=\"Apple-converted-space\">\u00a0<\/span>Kurs stattfinden wu\u0308rde, und als er seine Mutter fragte, ob er daran teilnehmen k\u00f6nnte, sagte sie ja. Als sie ihn zu seinem ersten <em>Jiujitsu<\/em><span class=\"Apple-converted-space\">\u00a0<\/span>Unterricht fuhr, sagte er ihr, dass dies der glu\u0308cklichste Tag in seinem Leben sei und dass Kampfkunst zu erlernen das war, was er mehr als alles andere wollte.<\/p>\n<p class=\"p1\">Er begann zun\u00e4chst fu\u0308r einige Jahre mit <em>Jiujitsu<\/em>. Dann kam er zum <em>Okinawa Karate<\/em>, dem <em>Shorin-Ryu<\/em>. Im <em>Shorin-Ryu<\/em> Karate<span class=\"Apple-converted-space\">\u00a0<\/span>machte er den vierten Schwarzgurt. Sp\u00e4ter kam er zur \u201eAmerican Kempo Association\u201c mit Simeon Eli als Lehrer. James Mitose brachte etwas, was sich \u201eold pine tree style\u201c<span class=\"Apple-converted-space\">\u00a0<\/span>nannte, von Japan nach Hawaii und unterrichtete Simeon Eli. So studierte er <em>Kenpo<\/em> mit Simeon Eli und bekam dort den zweiten Schwarzgurt. Er studierte auch mit dem \u201eAmerican Jiujitsu Institute\u201c, wo sie unterschiedliche Lehrer hatten.<\/p>\n<p class=\"p1\">Wally Jay war zwar mehr ein Kollege, aber er brachte ihm Einiges bei. Im <em>Jiujitsu<\/em><span class=\"Apple-converted-space\">\u00a0<\/span>erhielt er den vierten Schwarzgurt. Er war in der Lage, auf Hawaii von mehreren Lehrern zu lernen. Einige von ihnen brachten ihm schon fru\u0308h etwas <em>Bagua<\/em><span class=\"Apple-converted-space\">\u00a0<\/span>und <em>Hsing-I<\/em><span class=\"Apple-converted-space\">\u00a0 <\/span>bei. Aufgrund des Einflusses von Wally Jay ver\u00e4nderte sich sein <em>Jiujitsu<\/em><span class=\"Apple-converted-space\">\u00a0<\/span>in eine Richtung, die wir als <em>Chin Na<\/em><span class=\"Apple-converted-space\">\u00a0<\/span>Technik bezeichnen wu\u0308rden. Das ist zumindest ein Teil von Chris generellem Hintergrund.<\/p>\n<p class=\"p1\">Im College war Philosophie sein Hauptfach und sie war seine zweite Liebe neben der Kampfkunst. Er studierte Philosophie fu\u0308r viele Jahre. Er wollte seinen Master-Abschluss in Philosophie machen, aber die westlichen oder amerikanischen Schulen waren der \u00f6stlichen Philosophie gegenu\u0308ber nicht sonderlich freundlich eingestellt. Sein Wunsch war die \u00f6stliche und westliche Philosophie in seinen Schriften miteinander zu verbinden, aber er konnte keinen Referenten finden, der ihm dies in seiner Arbeit erlaubte.<\/p>\n<p class=\"p1\">Direkt nach dem College ging er ins Versicherungsgesch\u00e4ft. Er lernte seine Frau in der Gegend um Washington DC kennen, wo er am \u201eGeorge Mason College\u201c war und ging direkt in das Versicherungsgesch\u00e4ft. Sein Ziel war es, sich bis zum Versicherungsvermittler hochzuarbeiten, um die Freiheit zu haben, reisen und die Kampfku\u0308nste studieren zu k\u00f6nnen. Eine seiner Bemerkungen mir gegenu\u0308ber war, dass jeder Boss fu\u0308r den er gearbeitet hatte, ein Idiot war. (lacht)<\/p>\n<p class=\"p1\">Also kletterte er die Leiter immer h\u00f6her, bis zu der H\u00f6he des Vizepr\u00e4sidenten, von wo aus es nicht mehr wirklich weiter ging. Ihm wurden bessere Jobs angeboten und er wechselte auf dieser Ebene durch einige Firmen, aber das war so weit, wie er nach oben kommen konnte. Die normalen Versicherungen interessierten ihn nicht wirklich, fu\u0308r ihn war es lediglich eine Art, seinen Lebensunterhalt zu verdienen. Er lernte etwas kennen, das sich \u201einternationale Ru\u0308ckversicherung\u201c nannte und ging nach Seattle, um das dort fu\u0308r einige Jahre zu studieren. Dort traf er Taki Kimura und die Jeet Kune Do<span class=\"Apple-converted-space\">\u00a0<\/span>Verbindung. Nach zwei Jahren in Seattle bekam er das Angebot nach Hannover zu gehen, um dort fu\u0308r die \u201eHannover Ru\u0308ck\u201c zu arbeiten. Seine Aufgabe war es, eine Ru\u0308ckversicherungs-Abteilung aufzubauen, die mit der \u201eLords of London Insurances\u201c<span class=\"Apple-converted-space\">\u00a0<\/span>und den von ihr angebotenen Produkten konkurrieren konnte. Das war ein interessanteres Feld innerhalb der Versicherungen fu\u0308r ihn, aber wenn ich ihn u\u0308ber die Jahre hinweg fragte, wie sein Job sei, sagte er immer: \u201eEin Job ist ein Job, wei\u00dft du?!\u201c<\/p>\n<p class=\"p1\">Irgendwann wurde er es leid, wie er sagte: \u201eDiesen Leuten, die schon so viel Geld haben, dabei zu helfen, noch mehr Geld zu verdienen\u201c, dass er sich dazu entschied, aufzuh\u00f6ren. Die \u201eHannover Ru\u0308ck\u201c schickte ihn zuru\u0308ck in die Gegend von New York, um eine Filiale in den USA aufzubauen. Letztlich war er nicht mit den Versprechungen zufrieden, die ihm gemacht wurden, und so ku\u0308ndigte er schlie\u00dflich. Im letzten Jahr blieb er einfach nur in Atlanta und hatte einige Jobs, die er in Erw\u00e4gung zog, die aber letztendlich nicht zustande kamen. \u201eHannover Ru\u0308ck\u201c war die letzte Firma, fu\u0308r die er gearbeitet hat.<\/p>\n<p class=\"p1\"><strong>Als Mr. Casey nach Taiwan gegangen ist, um von Shen Muo Hui, Wang Shu Shen und all den anderen zu lernen, muss es gerade in dieser Zeit, besonders als Westler, doch sehr schwierig gewesen sein, an diese Leute heranzukommen. Wie ist ihm das gelungen?<\/strong><\/p>\n<p class=\"p1\">Es war eine Kombination von mehreren Dingen. In Atlanta hatte er Verbindung zur \u201eKoushu Federation\u201c bekommen. Ich glaube, er fing 1971 in Taiwan an, hatte aber schon vorher mit dem chinesischen Generalkonsul der taiwanesischen Regierung in Atlanta Kontakt aufgenommen. Er unterrichtete den Sohn des Generalkonsuls, daher kam die Verbindung zustande. In Caseys erstem Buch, dem Koushu-Buch, ist eine Abbildung des Sohnes mit dem Breitschwert in verschiedenen Positionen zu sehen. Diese Verbindung verschaffte ihm Zugang zu Taiwan.<\/p>\n<p class=\"p1\">Die Koushu Federation war ein Teil des Bildungsministeriums, wurde aber finanziell nicht gef\u00f6rdert. Sie hatten einfach nicht das Geld dafu\u0308r. Was sie jedoch machten, war die j\u00e4hrliche Veranstaltung eines Turniers. Mit dabei waren alle Schulen aus Taiwan, die Auffu\u0308hrungen und \u00c4hnliches machten. Casey hatte Robert Smiths Buch \u201eChinese Boxing\u201c gelesen, in dem er von diesen Lehrern sprach, und Casey traf schlie\u00dflich einen Gro\u00dfteil von ihnen.<\/p>\n<p class=\"p1\"><img decoding=\"async\" class=\"alignleft wp-image-15228 size-full\" src=\"http:\/\/chinese-boxing-institute.de\/wp-content\/uploads\/2018\/07\/Cravens-chang.jpg\" alt=\"\" width=\"482\" height=\"363\" \/>Er ging also nach Taiwan und hatte irgendwie einen Deal mit der \u201eKoushu Federation\u201c abgeschlossen, so in der Art: \u201eIhr gebt mir Zugang zu einigen dieser Lehrer und ich gebe Geld in die \u201eKoushu Federation\u201c, sodass die Organisation etwas besser finanziert ist.\u201c So kam er hinein. Zudem hatte er einige Lehrer, so wie Tao Ping Siang, den er bereits in Seattle getroffen hatte. Tao Ping Siang war seine Verbindung zu einigen der anderen Lehrer. Meister Tao kannte scheinbar jeden und war sehr gut vernetzt. Mr. Casey war keine immer einfache Pers\u00f6nlichkeit, aber er verstand, dass er, wenn er etwas haben wollte, selbst auch etwas flexibler sein musste.<\/p>\n<p class=\"p1\">Zu dieser Zeit verdiente er recht gut, also bezahlte er auch seine Lehrer sehr, sehr gut. Und er war durchweg loyal, er machte keine Sachen, die sie nicht wollten. Genauer gesagt mochten einige Lehrer nicht, dass er mit anderen Lehren studierte. Einiges von dem \u00e4nderte sich gerade, aber es gab immer noch einige Lehrer mit sehr traditionellen Ansichten. Sie mochten ihn sehr und die Tatsache, dass er ernsthaft bei der Sache war und sie nicht ausnutzte, sie gut bezahlte und sie bei seiner Ru\u0308ckkehr sehen konnten, dass er hart trainiert hatte und loyal war, brachte ihm bei einigen von ihnen mehr und mehr Vertrauen ein. Er erz\u00e4hlte mir, dass er bei einigen Lehrern Fehler gemacht hatte, einige, bei denen er wu\u0308nschte, das w\u00e4re nicht passiert, weil er dadurch den Zugang zu ihnen verloren hatte. Aber er lernte daraus und wurde mit der Zeit immer flexibler und schlie\u00dflich hatte er einen guten Kern von Leuten, die ihm viel beibringen konnten<\/p>\n<p class=\"p1\"><strong>Fu\u0308r welchen Zeitraum reiste er nach Taiwan?<\/strong><\/p>\n<p class=\"p1\">Ich wei\u00df, dass er Verbindungen hatte, weil ich Bilder von ihm mit der \u201eKoushu Federation\u201c von 1971 habe. Also wahrscheinlich einige Zeit davor. Ich kann dir nicht sagen, wie lange vor 1971. Er ist 1986 gestorben, also hatte er etwa 15 oder 16 Jahre, aber ich wei\u00df nicht, wie lange das in die sp\u00e4ten 60er Jahre zuru\u0308ckgeht. Ich wei\u00df es einfach nicht.<\/p>\n<p class=\"p1\"><strong>Wie alt war er, als er starb?<\/strong><\/p>\n<p class=\"p1\">Nur 39 Jahre alt.<\/p>\n<p class=\"p1\"><strong>Was ist passiert?<\/strong><\/p>\n<p class=\"p1\">Als er mit einigen seiner Lehrer u\u0308ber dieses Angebot sprach, war speziell Lo Man Kam streng dagegen. Seine Lehrer mochten die Japaner nicht besonders und waren dagegen, die chinesische Kampfkunst mit den Japanern zu teilen.<\/p>\n<p class=\"p1\">Im September &#8217;86 begann er wirklich starke Kopfschmerzen zu bekommen. Er hatte zwar schon immer Kopfschmerzen gehabt, aber diese waren wirklich schlimm und hielten fu\u0308r einen langen Zeitraum an. Mr. Casey war Medikamenten gegenu\u0308ber schon immer sensibel gewesen, also nahm er sie nicht wirklich gerne. Aber als die Kopfschmerzen so stark wurden, waren die \u00c4rzte der Meinung, dass es sich durchaus um einen Tumor handelt k\u00f6nnte. Er sollte einen Kontrastmittel-Test machen, wobei Kontrastmittel in den K\u00f6rper gespritzt wird. Aber Casey wollte diesen Test nicht machen, weil seine Mutter einmal beinahe bei einem solchen Test gestorben war. Also versuchte er es einige Wochen mit der Einnahme von Schmerzmitteln gegen die Kopfschmerzen. Sie waren bei Nacht schlimmer und nachdem er die Schmerzmittel u\u0308ber einige Tage eingenommen hatte, sagte er: \u201eIch kann das nicht weiter machen, ich bin vollkommen nutzlos!\u201c Mr. Casey, wenn man ihn kannte, war sehr stolz auf seinen scharfen Verstand und ihm war klar, dass dieser ihm alles erm\u00f6glicht hatte, was er in diesem Leben erreicht hatte.<\/p>\n<p class=\"p1\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-15229\" src=\"http:\/\/chinese-boxing-institute.de\/wp-content\/uploads\/2018\/07\/CG-Casey.jpg\" alt=\"\" width=\"360\" height=\"491\" srcset=\"https:\/\/chinese-boxing-institute.de\/wp-content\/uploads\/2018\/07\/CG-Casey.jpg 360w, https:\/\/chinese-boxing-institute.de\/wp-content\/uploads\/2018\/07\/CG-Casey-220x300.jpg 220w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/>Weil ich also sein Denken und seine Philosophie verstand, war mir klar, dass das Risiko bestand, dass er sich das Leben nehmen k\u00f6nnte. Aber er hielt mit den Kopfschmerzen die ganze Zeit von September bis Dezember durch und schaffte es bis zum 13. Dezember. In der ganzen Zeit sagte er mir nicht, was los ist. Er rief mich in dieser Zeit oft an und wir hatten Unterhaltungen und einige dieser Unterhaltungen fanden mitten in der Nacht statt. Er begann zu erz\u00e4hlen und pl\u00f6tzlich \u00e4nderte er sich und war nicht mehr Mr. Casey. Was er erz\u00e4hlte, ergab im Zusammenhang zu seiner normalen Kommunikation keinen Sinn mehr. Es war nichts Dramatisches, was er sagte, aber es war klar, dass er nicht er selbst war w\u00e4hrend dieser Zeit mit gro\u00dfen Schmerzen. Ich wollte mit seiner Frau daru\u0308ber sprechen, aber nicht, wenn er mit im Raum war.<\/p>\n<p class=\"p1\">Es war schwierig, sie einfach anzurufen und zu fragen, was los sei. Das waren die einzigen Anzeichen, dass etwas nicht stimmte, denn in diesem Zeitraum hatte er mit mir eine Vereinbarung getroffen. Ich arbeitete zu dieser Zeit in einer Fabrik als Werksleiter, hatte drei kleine Kinder, arbeitete lange und konnte daher nicht so oft zu ihm fahren. Es sind nur zwei Stunden Fahrt, aber ich konnte nicht oft runter fahren. Also sagte er: \u201eDa du nicht so oft hier runter kommen kannst, warum unterrichte ich nicht samstags einige deiner Schu\u0308ler fu\u0308r drei Stunden, das wu\u0308rde dir helfen, einiges indirekt u\u0308ber sie zuru\u0308ckzubekommen\u201c.<\/p>\n<p class=\"p1\">Also verpflichteten sich etwa zwanzig meiner Schu\u0308ler dazu, jeden Samstag zu ihm zu fahren. Sie fuhren u\u0308ber 10 Wochen dorthin, bis zu der Zeit seines Todes. Sie bemerkten nichts &#8230; natu\u0308rlich wussten sie, dass er seltsam ist, natu\u0308rlich wussten wir alle, dass er seltsam ist (lacht), also schauten sie auch nicht nach irgendwelchem ungew\u00f6hnlichen Verhalten. Ich war nicht da, also kann ich nicht sagen, ob irgendetwas anders war, aber er war in der Lage, innerhalb dieser drei Unterrichtsstunden zu funktionieren. Aber als ich mich sp\u00e4ter mit seiner Frau traf, erz\u00e4hlte sie mir die ganze Geschichte u\u0308ber das, was passiert war. Ich hatte eine Ahnung, dass etwas nicht stimmte, von den Unterhaltungen, die wir hatten, aber ich wusste nicht, was es war. Er versuchte, durchzuhalten, aber ich denke, ihm ist es bewusst geworden. Seine Frau war dabei, als er sich mit mir unterhielt. Und sie erz\u00e4hlte mir, dass sie ihm einmal, nachdem er aufgelegt hatte, erz\u00e4hlte, was er gerade zu mir gesagt hatte und er das nicht glauben konnte. Also hat er sich zuletzt das Leben genommen, zweifellos weil er wusste, dass sein Verstand nicht mehr derselbe sein wu\u0308rde.<\/p>\n<p class=\"p1\"><strong>Wie hast du danach weiter gemacht?<\/strong><\/p>\n<p class=\"p1\">Es war natu\u0308rlich ein Schock, aber unter den Umst\u00e4nden und mit dem Verst\u00e4ndnis fu\u0308r seine Art des Denkens konnte ich nachvollziehen, warum er das tat. Aber zuerst ziehst du dich zuru\u0308ck und sagst dir, wei\u00dft du (pausiert), da war noch so viel, das ich lernen wollte. Aber daru\u0308ber musst du hinwegkommen. Und dann habe ich mich zusammen genommen und habe mir gesagt ok, lasst uns daru\u0308ber sprechen, lasst uns daran arbeiten und lasst uns das bewahren, was seine Lehre und sein Wesen ausgemacht hat. Lasst uns sehen, ob wir daraus etwas Zusammenh\u00e4ngendes aufbauen k\u00f6nnen. Natu\u0308rlich war es fu\u0308r mich eine gro\u00dfe Hilfe, dass er Leute wollte, die fu\u0308r sich selbst denken und nicht einfach nur etwas kopieren. Ich hatte viele Notizen und viele Konversationen und so viel Material, das er mir beigebracht hatte.<\/p>\n<p class=\"p1\">Also habe ich, anstatt die Tatsache zu betrauern, dass ich noch mehr von ihm h\u00e4tte lernen k\u00f6nnen, mir die Frage gestellt: \u201eWarum war er so gut und was hat er zusammengestellt, das so besonders gewesen ist?\u201c Das war fu\u0308r die folgenden Jahre das, was ich versucht habe. Und das war, als mir bewusst wurde, dass mehr nicht notwendigerweise auch mehr ist. Es geht darum zu verstehen, was man dir gegeben hat, und zu verstehen, warum er so gut war und was ihn so gut werden lie\u00df. Das war der ganze Prozess.<\/p>\n<p class=\"p1\">Ich hatte einen oder zwei Langzeitschu\u0308ler, die wirklich richtig niedergeschlagen waren. Aber sie haben mit mir durchgehalten und sind da auch wieder rausgekommen. Zu Beginn war es wirklich ein richtiger Schock, aber das Leben muss weiter gehen und so habe ich versucht, das Beste aus der Situation zu machen, weil ich das, was er unterrichtet hat, wertsch\u00e4tze, speziell innerhalb der Kampfku\u0308nste. Wie er in der Lage gewesen war, so viel aufzunehmen und es fu\u0308r das zu sehen, was es war, und in der Lage war, die wichtigsten Komponenten zusammenzufu\u0308gen, diese Art des Denkens sch\u00e4tze ich sehr.<\/p>\n<p class=\"p1\"><strong>Sp\u00e4ter hast du Kontakt zum <em>Chen Tai Chi<\/em><span class=\"Apple-converted-space\">\u00a0<\/span>bekommen und das weiter studiert. So weit ich wei\u00df, hast du zuerst <em>Yang Style Tai Chi<\/em><span class=\"Apple-converted-space\">\u00a0<\/span>und die <em>Cheng Man Ching Form<\/em> von Tao Ping Siang gelernt. Was hat dich am <em>Chen Tai Chi<\/em><span class=\"Apple-converted-space\">\u00a0<\/span>interessiert?<\/strong><\/p>\n<p class=\"p1\">Um genau zu sein, habe ich zuerst Caseys Version von Tao Ping Siangs Form gelernt. Nach Mr. Caseys Tod begann Meister Tao fu\u0308r ein paar Wochen jedes Jahr zu mir zu kommen und ich habe die kurze <em>Yang Form<\/em> direkt von ihm gelernt. So war ich in der Lage, die Unterschiede zu sehen, zwischen dem, was Casey gemacht hatte, und dem, was Meister Tao unterrichtete. Aber von &#8217;86 bis &#8217;93 war ich ohne Lehrer, au\u00dfer Meister Tao, der jedes Jahr fu\u0308r ein paar Wochen zu mir kam. Dann kam eines Tages ein Typ in meine Schule, ein junger Mann aus China. Er war sehr leicht und machte nicht den Eindruck eines gro\u00dfen K\u00e4mpfers, aber als er sein <em>Chen Tai Chi<\/em><span class=\"Apple-converted-space\">\u00a0<\/span>demonstrierte &#8230;<\/p>\n<p class=\"p1\">Mr. Casey hatte mal zu mir gesagt, dass ich, falls ich einmal gutes <em>Chen Tai Chi<\/em><span class=\"Apple-converted-space\">\u00a0<\/span>sehe, dran bleiben sollte, weil es eine gute Kunst ist. Ich hatte bislang schon Einiges gesehen, aber nie hatte es sich richtig angefu\u0308hlt. Da gab es Leute, die sich beim <em>fa jing<\/em>, dem schnellen Loslassen von Kraft, auf eine Art schu\u0308ttelten, die nicht richtig wirkte. Ihre Kraft kam mir unecht vor, es sah aus, als h\u00e4tte sie keine Substanz. Ich hatte zwar die Gelegenheiten, aber mich hatte bislang nichts u\u0308berzeugt.<\/p>\n<p class=\"p1\">Als dieser Typ zu mir kam und seine Form demonstrierte, war ich von einigen Sachen wirklich beeindruckt und stellte ihm Fragen zu seinem <em>Tai Chi<\/em>. Ich fragte ihn, ob sein <em>Tai Chi<\/em><span class=\"Apple-converted-space\">\u00a0 <\/span>zum K\u00e4mpfen geeignet sei oder nur fu\u0308r die Gesundheit. Er sagte: \u201eWir glauben, was gut fu\u0308r das eine ist, ist auch gut fu\u0308r das andere.\u201c Das war eine Antwort, die ich nicht erwartet hatte und auch nicht gewohnt war zu h\u00f6ren. Mr. Casey hatte kein spezielles Interesse am gesundheitlichen Aspekt, ihn interessierte nur der Kampfkunst-Hintergrund. Der Kerl hingegen machte die Aussage, dass, wenn du etwas fu\u0308r deine Gesundheit tust, das nicht nachteilig, sondern eher nu\u0308tzlich fu\u0308r den k\u00e4mpferischen Aspekt sein kann.<\/p>\n<p class=\"p1\">Was mir das <em>Chen Tai Chi<\/em><span class=\"Apple-converted-space\">\u00a0<\/span>u\u0308ber die Zeit hin gezeigt hat, war, dass mir die Struktur des K\u00f6rpers nicht im Detail beigebracht worden war, nicht die Regeln des Kwa<span class=\"Apple-converted-space\">\u00a0<\/span>(der Struktur um das Becken) und wie alles ausbalanciert wird. Meine <em>Chen Tai Chi<\/em><span class=\"Apple-converted-space\">\u00a0<\/span>Lehrer hatten viele Details u\u0308ber den strukturellen Aufbau und viele gro\u00dfartige Wege, die Entspannung des K\u00f6rpers zu unterrichten, anstatt nur zu sagen, dass man sich mehr entspannen muss.<\/p>\n<p class=\"p1\">Ich glaube nicht, dass Mr. Casey diesen Dingen begegnet ist. Wenn Meister Tao etwas daru\u0308ber wusste, dann hat er es nicht unterrichtet. Meister Tao unterrichtete sowieso auf die Art, die Westler nicht m\u00f6gen: \u201eDu folgst mir und kannst es fu\u0308r dich selbst rausfinden. Stell keine Fragen!\u201c Aber als dann seine letzten Jahre angebrochen waren, hat er angeregt, Fragen zu stellen, aber so war es eben am Anfang und ist wahrscheinlich auch die Art, wie Meister Tao Casey unterrichtet hatte.<\/p>\n<p class=\"p1\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-15230 size-full\" src=\"http:\/\/chinese-boxing-institute.de\/wp-content\/uploads\/2018\/07\/Craven-Tai-Chi.jpg\" alt=\"\" width=\"471\" height=\"531\" srcset=\"https:\/\/chinese-boxing-institute.de\/wp-content\/uploads\/2018\/07\/Craven-Tai-Chi.jpg 471w, https:\/\/chinese-boxing-institute.de\/wp-content\/uploads\/2018\/07\/Craven-Tai-Chi-266x300.jpg 266w\" sizes=\"(max-width: 471px) 100vw, 471px\" \/>Es gibt einen definitiven Unterschied in der Art und Weise, wie viele Leute ihren K\u00f6rper strukturieren, und dem, was die Leute tun, die innere Kampfkunst machen. Fu\u0308r mich war das nicht nur im <em>Chen Tai Chi<\/em><span class=\"Apple-converted-space\">\u00a0<\/span>so. <em>Hsing-I<\/em>-Leute und viele <em>Bagua<\/em>-Leute haben die gleichen Regeln. Es war kein Eigentum des <em>Chen Tai Chi<\/em>, aber es war der erste Lehrer, der das mir gegenu\u0308ber hervorgehoben hat.<\/p>\n<p class=\"p1\">Einer der Konflikte war das starke Nach-vorne-Kippen der Hu\u0308fte, das Lo Man Kam seinen <em>Wing Chun<\/em>-Leuten beibrachte und auf das Mr. Casey sich bezog. Wenn man Mr. Casey bei seinen Sachen zusah, zeigte er die meiste Zeit keine nach vorne gekippte Hu\u0308fte, besonders keine so stark nach vorne gekippte Hu\u0308fte.<\/p>\n<p class=\"p1\">Das alles brachte mich dazu, eine Menge nachzudenken, zu trainieren und auszuprobieren. Mir wurde klar, dass es dem, was wir bereits im<em> Chinese Boxing<\/em> gelernt hatten, nur helfen wu\u0308rde. Ich hatte nicht das Gefu\u0308hl, von den <em>Chen Tai Chi<\/em>-Leuten etwas u\u0308ber das K\u00e4mpfen zu lernen, was ich nicht schon vorher wusste. Aber die strukturellen Dinge helfen der ganzheitlichen Bewegung, der Projektion, helfen bei so vielen Sachen, die wir schon kennen. Fu\u0308r mich ist das wirklich ein fehlendes Puzzleteil gewesen und das ist meine Schlussfolgerung daraus.<\/p>\n<p class=\"p1\">Aus dem Grund bin ich den Dingen weiter nachgegangen und bin technisch gesehen immer noch ein Schu\u0308ler von Chen Xiao Wang dru\u0308ben in China. Da er aber sehr beru\u0308hmt ist und viel reist, gibt es nicht mehr viel Zugang zu ihm. \u00dcber viele Jahre hinweg ist er jedoch hierher gekommen und wir hatten einige wirklich gute Sessions.<\/p>\n<p class=\"p1\">Es ist jedoch nicht der k\u00e4mpferische Aspekt, wei\u00dft du. Ich habe kein System gefunden, das ich besser finde als Mr. Caseys Kampfsystem. Es ist das Verst\u00e4ndnis dafu\u0308r, deinen K\u00f6rper dazu zu bringen, mehr fu\u0308r ganzheitliche Bewegung, Entspannung usw. zu tun. Es gibt die Dinge, die mich fu\u0308r die <em>Chen<\/em> Methode gewonnen haben. Ich bin kein strikter Vertreter fu\u0308r <em>Chen Tai Chi<\/em>. Bei \u00e4lteren Leuten halte ich es fu\u0308r wichtig, gesunde Bewegung zu machen, und da ist <em>Tai Chi<\/em> eine gro\u00dfartige Sache. Genau genommen kann man die Sachen, die ich im <em>Chen Tai Chi<\/em><span class=\"Apple-converted-space\">\u00a0<\/span>gelernt habe, auch leicht auf das <em>Yang Tai Chi<\/em><span class=\"Apple-converted-space\">\u00a0<\/span>anwenden.<\/p>\n<p class=\"p1\">Wie ich schon sagte, diese Dinge sind kein <em>Chen Tai Chi-<\/em>Eigentum, es hat nur einige gute Lehrer, die Sachen mit mir geteilt haben, die ich sonst nirgends gelernt habe.<\/p>\n<p class=\"p1\"><strong>Um noch mal zu den Trainingsmethoden, die u heutzutage anwendest, zuru\u0308ckzukommen. Was ist deiner Meinung nach ein guter Weg fu\u0308r einen Anf\u00e4nger, das Verwurzeln, die Struktur und den Fluss von Energie fu\u0308r sich zu entdecken?<\/strong><\/p>\n<p class=\"p1\">Die Struktur kann innerhalb des <em>Tai Chi<\/em>, aber auch im <em>Chinese Boxing<\/em> unterrichtet werden. Es muss eine spezielle Art und Weise der Bewegung entwickelt werden. Dann kannst du fragen: \u201eWie kann ich meine Bewegungen aus dem <em>Chinese Boxing<\/em> Encounter mit all dem u\u0308ben?\u201c Das kannst du, aber die langsame Bewegung hat eine tiefere, eine pr\u00e4zisere Entwicklung, weil du all die Sachen, die du falsch machst, direkt bemerken kannst. Wenn du dich richtig schnell bewegst, wirst du es nie genau wissen. Ich wu\u0308rde sagen, <em>Tai Chi<\/em> oder <em>Bagua<\/em>\u00a0oder <em>Hsing-I<\/em> zu lernen, ist eine M\u00f6glichkeit, es herauszufinden.<\/p>\n<p class=\"p1\">Aber deine ganze Zeit dafu\u0308r zu verwenden, wird dir nicht viel Fortschritt im K\u00e4mpfen bringen. Es kann also gemischt werden, es ist m\u00f6glich, langsame Sachen im Encounter und in den Solo-Sachen zu machen, wobei dir ein Lehrer dabei helfen kann, das Verwurzeln zu lernen und zu entspannen, w\u00e4hrend du dich bewegst, ohne dass du eine Form lernst.<\/p>\n<p class=\"p1\">Du kannst sagen, dass es schwer ist, das zu tun, was einige Leute entwickelt haben. Selbst Casey, er hasste Form, aber er u\u0308bte wirklich viel\u00a0<em>Bagua<\/em>, <em>Tai Chi<\/em> und <em>Hsing-I<\/em>, weil alle Lehrer, die er respektierte, sagten: \u201eDas ist gut fu\u0308r dich.\u201c<\/p>\n<p class=\"p1\">Es lehrt dich fu\u0308r eine gewisse Zeit, unten zu bleiben: zehn, zwanzig, drei\u00dfig Minuten in der Wurzel. Innerhalb der Wurzel bringt es dir bei, dich so zu bewegen, dass du dich nicht u\u0308berm\u00e4\u00dfig ausdehnst in deinen Beinen, deinen Schritten. Du bleibst in einer ver\u00e4nderlichen Art der Bewegung, es lehrt dich, fu\u0308r eine l\u00e4ngere Periode eine ganzheitliche Bewegung beizubehalten.<\/p>\n<p class=\"p1\">Im <em>Chinese Boxing<\/em> habe ich herausgefunden, dass, wenn ich Anf\u00e4nger unterrichte und Leute im Encounter korrigiere \u2013 ob das im Entry oder Yield and Counter oder Stop Hit oder was auch immer ist \u2013, es in neun von zehn F\u00e4llen darauf hinausl\u00e4uft, dass ihre Schritttechnik schlecht ist und sie zu schnell sind. Sie haben in dem Fall nicht die Disziplin des korrekten Gehens entwickelt. Zum anderen bleiben sie nicht unten, sie kommen statt dessen hoch. Ihre Energie kommt hoch. Es wird langsam alt, die Leute werden es leid, aber die meiste Zeit sind es immer die gleichen Korrekturen. Solange, bis sie es endlich so leid werden, dass sie anfangen, es zu lernen, und wenn sie es dann gelernt haben, wird ihnen klar: \u201eWow, ich habe soviel mehr Kontrolle, ich kann so viel mehr machen, wenn ich unten und in einer guten Position bleibe.\u201c<\/p>\n<p class=\"p1\">Es ist einfach so, dass das K\u00e4mpfen eine Energie in dir freisetzt, die dem Untenbleiben entgegenwirkt. In der Lage zu sein, w\u00e4hrend des K\u00e4mpfens in diesem Zustand zu bleiben, ist die gr\u00f6\u00dfte Herausforderung im Unterricht, weil es nicht besonders interessant ist oder viel Spa\u00df macht, zu lernen unten zu bleiben und das auch noch richtig zu machen. (lacht)<\/p>\n<p class=\"p1\">Aber es sind die Basics, die dich richtig gut werden lassen, und schau dir an, was Casey machen konnte. Er konnte unten bleiben und er konnte akkurat gehen. Er war kein gro\u00dfer Athlet, aber er konnte die Energie kontrollieren, weil er in der Lage war, einige dieser fundamentalen Dinge zu beherrschen, die ihn richtig gut werden lie\u00dfen. Also machen wir viel Basics und wenn jemand eine Technik lernen m\u00f6chte, fein. Ok, jetzt kann er oder sie die Technik in den Encounter einbringen. Wenn er das hinbekommt, kriegt er das auch langsam hin? Kann er in der langsamen Bewegung auch unten bleiben? Langsam ist die einfachste Art, das hinzubekommen. Es wird schwerer, wenn du schneller wirst.<\/p>\n<p class=\"p1\">Ich wu\u0308rde den Leuten, die es ernst meinen, empfehlen, neben dem <em>Chinese Boxing<\/em> auch eine der inneren Bewegungsarten zu machen. Ein <em>Chinese Boxing<\/em>-Lehrer muss wissen, wie er diese beiden Sachen zusammenfu\u0308hrt. Das war wirklich das, wozu Casey in der Lage war.<\/p>\n<p class=\"p1\"><strong>Wo siehst du das Chinese Boxing Institute in der Zukunft?<\/strong><\/p>\n<p class=\"p2\">Diese Frage hat eine ermutigende Antwort. (lacht) Es ist so, dass ich eine Gruppe ju\u0308ngerer Schu\u0308ler habe. Ich sage ju\u0308nger, sie sind in ihren Drei\u00dfigern oder Vierzigern. Eine ju\u0308ngere Gruppe in Tennessee, die es wirklich ernst meint und wirklich Fortschritte macht, und das ist ermutigend fu\u0308r mich. Das Problem ist, dass ich in meinen Sechzigern bin, und viele meiner Schu\u0308ler sind etwa in demselben Alter und viele von ihnen unterrichten nicht, um davon zu leben. Ich sehe, dass manche Dinge einfach aussterben k\u00f6nnen. Mann fragt sich oft, wie das passieren kann. Es liegt daran, dass niemand aus den ju\u0308ngeren Generationen daran Interesse hat. Ein Teil der Verantwortung k\u00f6nnte darin liegen, dass die \u00e4ltere Generation keine Lust hat zu unterrichten. Einiges sind einfach Generationslu\u0308cken, speziell in der modernen Gesellschaft. Die Leute hier lernen <em>MMA<\/em> (Mixed Martial Arts) und sie lernen <em>Jiujitsu<\/em>. Das sind zur Zeit die popul\u00e4ren Kampfku\u0308nste hier bei uns. Und sie machen sich u\u0308ber die traditionellen Kampfku\u0308nste lustig bis hin zum <em>Chinese Boxing<\/em>.<\/p>\n<p class=\"p1\">Sie wissen nicht, was es ist, es ist nie wirklich bekannt geworden, es ist ein Kunstbegriff. Du kannst es in Energy Boxing<span class=\"Apple-converted-space\">\u00a0<\/span>umbenennen und es wird nichts an seiner Popularit\u00e4t \u00e4ndern. (lacht) Es ist eine spezialisierte Kampfkunst und kein Sport. Wenn Dinge kein Sport sein k\u00f6nnen, nimmst du ihnen den Grund, warum sich die Leute damit besch\u00e4ftigen wollen. Die Zukunft liegt also darin, dass die ju\u0308ngeren Generationen es weiter tragen. Ich kann sagen, dass ich einige Hoffnung habe, denn ich habe Schu\u0308ler, die es wirklich ernst meinen und schon einige Jahre dabei sind. In Bezug auf ihr Alter sind sie wirklich schon ziemlich reif und ich beobachte viel Enthusiasmus bei ihnen im Moment. Es gibt also Hoffnung. Ich wei\u00df nicht, wie es in Deutschland ist, aber es gibt ein bisschen Hoffnung hier in den USA, nur nicht viele Leute.<\/p>\n<p class=\"p1\"><strong>Stehen im Moment neue Buchprojekte bei dir an?<\/strong><\/p>\n<p class=\"p1\">Ich hatte so viel zu tun, ich habe Tonnen von DVDs aufgenommen fu\u0308r Schu\u0308ler, die ich u\u0308berall im Land habe, doch bin ich zu vielen Sachen nicht gekommen, die ich die ganze Zeit schon machen wollte. Ich bin bereit fu\u0308r noch mindestens ein <em>Chinese Boxing<\/em>-Buch und das wird gr\u00f6\u00dftenteils kein \u201eWie-Buch\u201c werden, sondern zum gro\u00dfen Teil aus Theorie in Bezug auf den Encounter<span class=\"Apple-converted-space\">\u00a0<\/span>selbst bestehen. Da fu\u0308hle ich, dass ich noch einen Beitrag leisten kann.<\/p>\n<p class=\"p1\">Es ist nur so, dass das Schreiben eines Buchs sich finanziell weniger lohnt als das Produzieren der DVDs. Und es ist eine Frage der Zeit, da ich das Unterrichten fu\u0308r meinem Lebensunterhalt mache und das den Gro\u00dfteil meiner Zeit in Anspruch nimmt. Das ist der Ausblick. Wenn ich schreibe, muss ich rauskommen, und wenn ich rauskomme, mache ich viele Fortschritte. Ich habe eine Ehefrau, die Korrektur liest, und das ist eine gute Ausgangssituation, mir fehlt einfach nur die Zeit. (lacht!)<\/p>\n<p class=\"p1\"><strong>James Cravens, vielen Dank fu\u0308r das Gespr\u00e4ch!<\/strong><\/p>\n<h6>Bilder: James Cravens, Dirk Wetter<\/h6>\n<h3>Zur Person:<\/h3>\n<p class=\"p1\">James Cravens ist Pr\u00e4sident und Direktor des Chinese Boxing Institute International (CBII) und lebt in Coral Springs, Florida. James studiert die Kampfku\u0308nste seit 1965 und wurde 1973 direkter Schu\u0308ler von Christopher G. Casey, dem Gru\u0308nder des CBII. Er gibt Kurse und Seminare an vielen Orten in den USA und ist schon mehrmals als Kursleiter in Deutschland gewesen. Seit 1995 studiert er zudem Chen Tai Chi und ist seit 2006 offiziell ein direkter Schu\u0308ler von Chen Xiao Wang.<\/p>","protected":false},"excerpt":{"rendered":"<p>Ich habe 1973 angefangen, bei Mr. Casey zu trainieren. Zu dieser Zeit unterrichtete er haupts\u00e4chlich Kenpo und sein Chin Na. <\/p>\n","protected":false},"author":2,"featured_media":15225,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[119],"tags":[65,57,68,67,66,62,61,59,56,64,63],"_links":{"self":[{"href":"https:\/\/chinese-boxing-institute.de\/chinese-boxing-starten\/wp-json\/wp\/v2\/posts\/15224"}],"collection":[{"href":"https:\/\/chinese-boxing-institute.de\/chinese-boxing-starten\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/chinese-boxing-institute.de\/chinese-boxing-starten\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/chinese-boxing-institute.de\/chinese-boxing-starten\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/chinese-boxing-institute.de\/chinese-boxing-starten\/wp-json\/wp\/v2\/comments?post=15224"}],"version-history":[{"count":27,"href":"https:\/\/chinese-boxing-institute.de\/chinese-boxing-starten\/wp-json\/wp\/v2\/posts\/15224\/revisions"}],"predecessor-version":[{"id":16386,"href":"https:\/\/chinese-boxing-institute.de\/chinese-boxing-starten\/wp-json\/wp\/v2\/posts\/15224\/revisions\/16386"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/chinese-boxing-institute.de\/chinese-boxing-starten\/wp-json\/wp\/v2\/media\/15225"}],"wp:attachment":[{"href":"https:\/\/chinese-boxing-institute.de\/chinese-boxing-starten\/wp-json\/wp\/v2\/media?parent=15224"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/chinese-boxing-institute.de\/chinese-boxing-starten\/wp-json\/wp\/v2\/categories?post=15224"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/chinese-boxing-institute.de\/chinese-boxing-starten\/wp-json\/wp\/v2\/tags?post=15224"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}